{"id":16911,"date":"2021-12-28T20:03:37","date_gmt":"2021-12-28T20:03:37","guid":{"rendered":"https:\/\/nanovea.com\/?p=16911"},"modified":"2025-05-22T20:23:55","modified_gmt":"2025-05-22T20:23:55","slug":"microstructure-des-fossiles-par-profilometrie-3d","status":"publish","type":"post","link":"https:\/\/nanovea.com\/fr\/fossil-microstructure-using-3d-profilometry\/","title":{"rendered":"Microstructure des fossiles par profilom\u00e9trie 3D"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"16911\" class=\"elementor elementor-16911\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ec3d48 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ec3d48\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c477953\" data-id=\"c477953\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cec2c6e elementor-widget elementor-widget-heading\" data-id=\"cec2c6e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MICROSTRUCTURE FOSSILE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d107f9b elementor-widget elementor-widget-heading\" data-id=\"d107f9b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">EN UTILISANT LA PROFILOM\u00c9TRIE 3D<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73c118d elementor-widget elementor-widget-image\" data-id=\"73c118d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"217\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Fossils-Portable-Profilometer.jpg\" class=\"attachment-medium_large size-medium_large wp-image-16924\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97cc106 elementor-widget elementor-widget-heading\" data-id=\"97cc106\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pr\u00e9par\u00e9 par<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95aa94e elementor-widget elementor-widget-heading\" data-id=\"95aa94e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">DUANJIE LI, PhD<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c14383d elementor-widget elementor-widget-spacer\" data-id=\"c14383d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-753c1f3 elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"753c1f3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f2074e4 elementor-hidden-phone\" data-id=\"f2074e4\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b259d86\" data-id=\"b259d86\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62f2a44 elementor-widget elementor-widget-heading\" data-id=\"62f2a44\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">INTRODUCTION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ab0009 elementor-widget elementor-widget-text-editor\" data-id=\"9ab0009\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les fossiles sont les restes pr\u00e9serv\u00e9s de traces de plantes, d'animaux et d'autres organismes enfouis dans les s\u00e9diments sous d'anciennes mers, lacs et rivi\u00e8res. Les tissus mous du corps se d\u00e9composent g\u00e9n\u00e9ralement apr\u00e8s la mort, mais les coquilles dures, les os et les dents se fossilisent. Les caract\u00e9ristiques de surface de la microstructure sont souvent pr\u00e9serv\u00e9es lors du remplacement min\u00e9ral des coquilles et des os d'origine, ce qui donne un aper\u00e7u de l'\u00e9volution du temps et du m\u00e9canisme de formation des fossiles.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9a07fb elementor-widget elementor-widget-heading\" data-id=\"c9a07fb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">IMPORTANCE D'UN PROFILOM\u00c8TRE 3D SANS CONTACT POUR L'EXAMEN DES FOSSILES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e74abb9 elementor-widget elementor-widget-text-editor\" data-id=\"e74abb9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les profils 3D du fossile nous permettent d\u2019observer les caract\u00e9ristiques d\u00e9taill\u00e9es de la surface de l\u2019\u00e9chantillon fossile sous un angle plus rapproch\u00e9. La haute r\u00e9solution et la pr\u00e9cision du profilom\u00e8tre NANOVEA peuvent ne pas \u00eatre perceptibles \u00e0 l&#039;\u0153il nu. Le logiciel d&#039;analyse du profilom\u00e8tre propose une large gamme d&#039;\u00e9tudes applicables \u00e0 ces surfaces uniques. Contrairement \u00e0 d&#039;autres techniques telles que les palpeurs, le NANOVEA <a href=\"https:\/\/nanovea.com\/profilometers\/\">Profilom\u00e8tre 3D sans contact<\/a> mesure les caract\u00e9ristiques de la surface sans toucher l\u2019\u00e9chantillon. Cela permet de pr\u00e9server les v\u00e9ritables caract\u00e9ristiques de la surface de certains \u00e9chantillons fossiles d\u00e9licats. De plus, le profilom\u00e8tre portable mod\u00e8le Jr25 permet des mesures 3D sur les sites fossilif\u00e8res, ce qui facilite consid\u00e9rablement l&#039;analyse et la protection des fossiles apr\u00e8s excavation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbe0c25 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbe0c25\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5bda47b\" data-id=\"5bda47b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5986dd7 elementor-reverse-mobile elementor-section-full_width elementor-reverse-tablet elementor-section-height-default elementor-section-height-default\" data-id=\"5986dd7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-77e62ae\" data-id=\"77e62ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae83510 elementor-widget elementor-widget-text-editor\" data-id=\"ae83510\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">OBJECTIF DE MESURE<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5556e11 elementor-widget elementor-widget-text-editor\" data-id=\"5556e11\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><span style=\"font-size: 16.8px;\">Dans cette \u00e9tude, le profilom\u00e8tre NANOVEA Jr25 est utilis\u00e9 pour mesurer la surface de deux \u00e9chantillons de fossiles repr\u00e9sentatifs. La surface enti\u00e8re de chaque fossile a \u00e9t\u00e9 scann\u00e9e et analys\u00e9e afin de caract\u00e9riser ses caract\u00e9ristiques de surface, notamment la rugosit\u00e9, le contour et la direction de la texture.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7429702 elementor-widget elementor-widget-text-editor\" data-id=\"7429702\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">NANOVEA<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fda08d7 elementor-widget elementor-widget-text-editor\" data-id=\"fda08d7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">Jr25<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48491b2 elementor-align-left learn-more-about-instrument elementor-widget elementor-widget-button\" data-id=\"48491b2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/nanovea.com\/instruments\/jr25\/\" id=\"profiler-lab-services\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">EN SAVOIR PLUS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a6b67e5\" data-id=\"a6b67e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-911a059 elementor-widget elementor-widget-image\" data-id=\"911a059\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nanovea.com\/instruments\/jr25\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"664\" height=\"733\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/08\/NANOVEA-Jr25-Portable-Profilometer.png\" class=\"elementor-animation-grow attachment-medium_large size-medium_large wp-image-12966\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e767880 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e767880\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da0379b\" data-id=\"da0379b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8511cd elementor-widget elementor-widget-heading\" data-id=\"b8511cd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FOSSILE DE BRACHIOPODE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c63d98 elementor-widget elementor-widget-text-editor\" data-id=\"3c63d98\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le premier \u00e9chantillon de fossile pr\u00e9sent\u00e9 dans ce rapport est un fossile de brachiopode, qui provient d'un animal marin poss\u00e9dant des \"valves\" (coquilles) dures sur ses surfaces sup\u00e9rieure et inf\u00e9rieure. Ils sont apparus \u00e0 la p\u00e9riode cambrienne, il y a plus de 550 millions d'ann\u00e9es.<\/p><p><span style=\"font-size: 16.8px;\">La vue 3D du scan est pr\u00e9sent\u00e9e dans la FIGURE 1 et la vue en fausses couleurs est pr\u00e9sent\u00e9e dans la FIGURE 2.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b45cc31 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b45cc31\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0b0b9cc\" data-id=\"0b0b9cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2752b9e elementor-widget elementor-widget-image\" data-id=\"2752b9e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"535\" height=\"501\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Shell-Fossil-Analysis.jpg\" class=\"attachment-large size-large wp-image-16919\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6275249\" data-id=\"6275249\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e87ac4d elementor-widget elementor-widget-image\" data-id=\"e87ac4d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"717\" height=\"521\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Brachiopod-Fossil-Scan-Profilometer.jpg\" class=\"attachment-large size-large wp-image-16939\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29d1a9c elementor-widget elementor-widget-text-editor\" data-id=\"29d1a9c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span class=\"fontstyle0\" style=\"color: #1b96cf;\">FIGURE 1: <\/span><span class=\"fontstyle0\" style=\"color: #1b96cf;\"><span style=\"color: #000000;\"><span class=\"fontstyle0\">Vue 3D de l'\u00e9chantillon de fossiles de brachiopodes.<\/span><br \/><\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45fdcda elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"45fdcda\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e2f7d1a\" data-id=\"e2f7d1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8f4b9fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8f4b9fc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bd8c3d0\" data-id=\"bd8c3d0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cdee2af\" data-id=\"cdee2af\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a3092b elementor-widget elementor-widget-image\" data-id=\"9a3092b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"418\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Brachiopod-Fossil-Study.jpg\" class=\"attachment-large size-large wp-image-16925\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e48813d elementor-widget elementor-widget-text-editor\" data-id=\"e48813d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span class=\"fontstyle0\" style=\"color: #1b96cf;\">FIGURE 2 :\u00a0<\/span><span class=\"fontstyle0\"><span style=\"color: #000000;\">Vue en fausses couleurs de l'\u00e9chantillon de fossiles de brachiopodes.<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d2205bf\" data-id=\"d2205bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-685a2b4 elementor-widget elementor-widget-text-editor\" data-id=\"685a2b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 16.8px;\">La forme globale a ensuite \u00e9t\u00e9 retir\u00e9e de la surface afin d'\u00e9tudier la morphologie et le contour de la surface locale du fossile de brachiopode, comme le montre la FIGURE 3. Une texture particuli\u00e8re de rainure divergente peut maintenant \u00eatre observ\u00e9e sur l'\u00e9chantillon de fossile de Brachiopode.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b41b021 elementor-widget elementor-widget-image\" data-id=\"b41b021\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"773\" height=\"318\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Shell-Fossil-Profilometry.jpg\" class=\"attachment-large size-large wp-image-16920\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60720fa elementor-widget elementor-widget-text-editor\" data-id=\"60720fa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span class=\"fontstyle0\" style=\"color: #1b96cf;\">FIGURE 3 :<\/span><span class=\"fontstyle0\" style=\"color: #1b96cf;\"><span style=\"color: #000000;\"><span class=\"fontstyle0\">\u00a0Vue des fausses couleurs et vue des lignes de contour apr\u00e8s la suppression du formulaire.<\/span><br \/><\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e20142b elementor-widget elementor-widget-text-editor\" data-id=\"e20142b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 16.8px;\">Un profil de ligne est extrait de la zone textur\u00e9e pour montrer une vue en coupe de la surface du fossile dans la FIGURE 4. L'\u00e9tude de la hauteur des pas mesure les dimensions pr\u00e9cises des caract\u00e9ristiques de la surface. Les rainures ont une largeur moyenne de ~0,38 mm et une profondeur de ~0,25 mm.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddb8c5d elementor-widget elementor-widget-image\" data-id=\"ddb8c5d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"243\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Shell-Fossil-Study.jpg\" class=\"attachment-large size-large wp-image-16921\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86f80bc elementor-widget elementor-widget-image\" data-id=\"86f80bc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"161\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Crinoid-Fossil-Study-Profilometer.jpg\" class=\"attachment-large size-large wp-image-16938\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5191c1e elementor-widget elementor-widget-text-editor\" data-id=\"5191c1e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span class=\"fontstyle0\" style=\"color: #1b96cf;\">FIGURE 4 :<\/span><span class=\"fontstyle0\" style=\"color: #1b96cf;\"><span style=\"color: #000000;\"><span class=\"fontstyle0\"> \u00c9tudes du profil des lignes et de la hauteur des marches de la surface textur\u00e9e.<\/span><br \/><\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1979bac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1979bac\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c969083\" data-id=\"c969083\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c67049 elementor-widget elementor-widget-heading\" data-id=\"9c67049\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FOSSILE DE TIGE DE CRINO\u00cfDE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f6f1994 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f6f1994\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-64b2fd4\" data-id=\"64b2fd4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff64916 elementor-widget elementor-widget-text-editor\" data-id=\"ff64916\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 16.8px;\">Le deuxi\u00e8me \u00e9chantillon de fossile est un fossile de tige de crino\u00efde. Les crino\u00efdes sont apparus dans les mers du Cambrien moyen, environ 300 millions d'ann\u00e9es avant les dinosaures.\u00a0<\/span><\/p><p><span style=\"font-size: 16.8px;\">\u00a0<\/span><\/p><p><span style=\"font-size: 16.8px;\">La vue 3D du scan est illustr\u00e9e \u00e0 la FIGURE 5 et la vue en fausses couleurs est illustr\u00e9e \u00e0 la FIGURE 6.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82d6755 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82d6755\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-06986b1\" data-id=\"06986b1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c66ad55 elementor-widget elementor-widget-image\" data-id=\"c66ad55\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"392\" height=\"534\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Crinoid-Fossil-Analysis.jpg\" class=\"attachment-large size-large wp-image-16926\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b26c0f\" data-id=\"2b26c0f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-954a105 elementor-widget elementor-widget-image\" data-id=\"954a105\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"661\" height=\"508\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Crinoid-Stem-Fossil-Study.jpg\" class=\"attachment-large size-large wp-image-16917\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9be55a4 elementor-widget elementor-widget-text-editor\" data-id=\"9be55a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span class=\"fontstyle0\" style=\"color: #1b96cf;\">FIGURE 5 : <\/span><span class=\"fontstyle0\" style=\"color: #1b96cf;\"><span style=\"color: #000000;\"><span class=\"fontstyle0\">Vue 3D de l'\u00e9chantillon de fossiles de crino\u00efdes.<\/span><br \/><\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ff3fa93 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ff3fa93\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cc3bbe9\" data-id=\"cc3bbe9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2571aa5 elementor-widget elementor-widget-text-editor\" data-id=\"2571aa5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 16.8px;\">L'isotropie et la rugosit\u00e9 de la texture de surface du fossile de tige de Crino\u00efde sont analys\u00e9es dans la FIGURE 7.\u00a0<\/span><\/p><p><span style=\"font-size: 16.8px;\">\u00a0<\/span><span style=\"color: var( --e-global-color-text );\">Ce fossile pr\u00e9sente une direction de texture pr\u00e9f\u00e9rentielle dans l'angle proche de 90\u00b0, ce qui conduit \u00e0 une isotropie de texture de 69%.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eedd47b\" data-id=\"eedd47b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-434c933 elementor-widget elementor-widget-image\" data-id=\"434c933\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"497\" height=\"368\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Crinoid-Fossil-Profilometry.jpg\" class=\"attachment-large size-large wp-image-16914\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5539591 elementor-widget elementor-widget-text-editor\" data-id=\"5539591\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #1b96cf;\">FIGURE 6 :<\/span><span style=\"color: #1b96cf;\"><span style=\"color: #000000;\">\u00a0Vue en fausses couleurs de la\u00a0<\/span><\/span><span style=\"color: #000000;\">Tige de crino\u00efde\u00a0<\/span><span style=\"color: #000000;\">\u00e9chantillon.<\/span><\/p><p style=\"text-align: center;\"><span style=\"color: #1b96cf;\"><span style=\"color: #000000;\">\u00a0<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d8cb364 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8cb364\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e39000d\" data-id=\"e39000d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-424834f elementor-widget elementor-widget-image\" data-id=\"424834f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"506\" height=\"248\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Crinoid-Fossil-Measurement.jpg\" class=\"attachment-large size-large wp-image-16913\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-30beef9\" data-id=\"30beef9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dac92d elementor-widget elementor-widget-image\" data-id=\"1dac92d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"444\" height=\"202\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Crinoid-Fossil-Isotropy-and-Roughness.jpg\" class=\"attachment-large size-large wp-image-16912\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b9d8ece elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b9d8ece\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ec5b3b6\" data-id=\"ec5b3b6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0cd55c elementor-widget elementor-widget-image\" data-id=\"e0cd55c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"234\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Fossil-Profilometry-Parameters.jpg\" class=\"attachment-large size-large wp-image-16918\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9522731 elementor-widget elementor-widget-text-editor\" data-id=\"9522731\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #1b96cf;\">FIGURE 7 :<\/span><span style=\"color: #1b96cf;\"><span style=\"color: #000000;\">\u00a0<\/span><\/span><span style=\"color: #000000;\">Isotropie de la texture de surface et rugosit\u00e9 du fossile de la tige du Crino\u00efde.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec9cf13 elementor-widget elementor-widget-text-editor\" data-id=\"ec9cf13\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 16.8px;\">Le profil 2D le long de la direction axiale du fossile de la tige du Crino\u00efde est pr\u00e9sent\u00e9 dans la FIGURE 8.\u00a0<\/span><\/p><p><span style=\"color: var( --e-global-color-text );\">La taille des pics de la texture de surface est assez uniforme.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e619d93 elementor-widget elementor-widget-image\" data-id=\"e619d93\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"211\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Crinoid-Stem-Fossil-Profile-Analysis.jpg\" class=\"attachment-large size-large wp-image-16916\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9001013 elementor-widget elementor-widget-image\" data-id=\"9001013\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"145\" src=\"https:\/\/nanovea.com\/wp-content\/uploads\/2021\/12\/Crinoid-Stem-Fossil-2D-Profile-Analysis.jpg\" class=\"attachment-large size-large wp-image-16915\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a0d003 elementor-widget elementor-widget-text-editor\" data-id=\"6a0d003\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #1b96cf;\">FIGURE 8 :<\/span><span style=\"color: #000000;\">\u00a0Analyse du profil 2D du fossile de la tige du Crino\u00efde.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c9a5b1 elementor-section-content-middle elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c9a5b1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f2d1204 elementor-hidden-phone\" data-id=\"f2d1204\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3f87574\" data-id=\"3f87574\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8843a9f elementor-widget elementor-widget-heading\" data-id=\"8843a9f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CONCLUSION<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18f7f2e elementor-widget elementor-widget-text-editor\" data-id=\"18f7f2e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-size: 16.8px;\">Dans cette application, nous avons \u00e9tudi\u00e9 de mani\u00e8re exhaustive les caract\u00e9ristiques de surface 3D d'un fossile de tige de brachiopode et de crino\u00efde \u00e0 l'aide du profilom\u00e8tre portable sans contact NANOVEA Jr25. Nous montrons que l'instrument peut caract\u00e9riser avec pr\u00e9cision la morphologie 3D des \u00e9chantillons fossiles. Les caract\u00e9ristiques de surface et la texture int\u00e9ressantes des \u00e9chantillons sont ensuite analys\u00e9es plus en d\u00e9tail. L'\u00e9chantillon de Brachiopode poss\u00e8de une texture de rainure divergente, tandis que le fossile de tige de Crino\u00efde montre une isotropie de texture pr\u00e9f\u00e9rentielle. Les scans de surface 3D d\u00e9taill\u00e9s et pr\u00e9cis s'av\u00e8rent \u00eatre des outils id\u00e9aux pour les pal\u00e9ontologues et les g\u00e9ologues pour \u00e9tudier l'\u00e9volution des vies et la formation des fossiles.<\/span><\/p><p><span style=\"color: var( --e-global-color-text ); background-color: rgba(255, 255, 255, 0);\">Les donn\u00e9es pr\u00e9sent\u00e9es ici ne repr\u00e9sentent qu'une partie des calculs disponibles dans le logiciel d'analyse. Les profilom\u00e8tres NANOVEA mesurent pratiquement n'importe quelle surface dans des domaines tels que les semi-conducteurs, la micro\u00e9lectronique, l'\u00e9nergie solaire, les fibres optiques, l'automobile, l'a\u00e9rospatiale, la m\u00e9tallurgie, l'usinage, les rev\u00eatements, la pharmacie, le biom\u00e9dical, l'environnement et bien d'autres encore.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b406b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b406b0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-727ba15\" data-id=\"727ba15\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ac3382 elementor-widget elementor-widget-heading\" data-id=\"6ac3382\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vous avez une application similaire ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-658ae6f elementor-align-justify open-chat elementor-widget elementor-widget-button\" data-id=\"658ae6f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">DISCUTER AVEC UN EXPERT MAINTENANT<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c2fa08 elementor-align-justify button-quote elementor-widget elementor-widget-button\" data-id=\"4c2fa08\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/nanovea.com\/contact-sales-form\/\" id=\"button-quote-bottom\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">OBTENIR RAPIDEMENT LES PRIX ET LES D\u00c9TAILS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>FOSSIL MICROSTRUCTURE USING 3D PROFILOMETRY Prepared by DUANJIE LI, PhD INTRODUCTION Fossils are the preserved remains of traces of plants, animals and other organisms buried in sediment under ancient seas, lakes and rivers. The soft body tissue usually decays after death, but the hard shells, bones and teeth fossilize. Microstructure surface features are often preserved [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16957,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[7,349,350,351,353,335],"tags":[],"class_list":["post-16911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-application-notes","category-laboratory-testing","category-profilometry-geometry-shape","category-profilometry-roughness-finish","category-profilometry-texture-grain","category-profilometry-testing"],"_links":{"self":[{"href":"https:\/\/nanovea.com\/fr\/wp-json\/wp\/v2\/posts\/16911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nanovea.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nanovea.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nanovea.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nanovea.com\/fr\/wp-json\/wp\/v2\/comments?post=16911"}],"version-history":[{"count":61,"href":"https:\/\/nanovea.com\/fr\/wp-json\/wp\/v2\/posts\/16911\/revisions"}],"predecessor-version":[{"id":24714,"href":"https:\/\/nanovea.com\/fr\/wp-json\/wp\/v2\/posts\/16911\/revisions\/24714"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nanovea.com\/fr\/wp-json\/wp\/v2\/media\/16957"}],"wp:attachment":[{"href":"https:\/\/nanovea.com\/fr\/wp-json\/wp\/v2\/media?parent=16911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nanovea.com\/fr\/wp-json\/wp\/v2\/categories?post=16911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nanovea.com\/fr\/wp-json\/wp\/v2\/tags?post=16911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}